{"id":3,"date":"2018-12-18T11:06:56","date_gmt":"2018-12-18T11:06:56","guid":{"rendered":"https:\/\/desplazamientos-francia.com\/it\/?page_id=3"},"modified":"2020-03-30T20:16:28","modified_gmt":"2020-03-30T18:16:28","slug":"politica-sulla-privacy","status":"publish","type":"page","link":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/","title":{"rendered":"Politica sulla privacy"},"content":{"rendered":"<h2><strong>POLITICA PER LA PROTEZIONE DEI DATI PERSONALI IN PRETIUM INTERMEDIARIOS, S.L.<\/strong><\/h2>\n<h2><strong>1. INTRODUZIONE<\/strong><\/h2>\n<p><strong>PRETIUM INTERMEDIARIOS S.L.<\/strong> informa che l&#8217;obiettivo della nostra politica sulla privacy \u00e8 proteggere al massimo livello la riservatezza dei dati personali ottenuti. PRETIUM INTERMEDIARIOS S.L. si impegna a mantenere la sicurezza dei dati forniti e ad adottare il livello di sicurezza della Legge sulla protezione dei dati personali previsto ex lege allo scopo di prevenire l&#8217;uso improprio, l&#8217;alterazione e l&#8217;accesso non autorizzato ai dati personali forniti. I dati saranno soggetti a trattamento informatizzato e inseriti nei nostri database, di cui PRETIUM INTERMEDIARIOS S.L. \u00e8 proprietaria e unica responsabile, essa societ\u00e0 utilizzer\u00e0 i dati personali solo in conformit\u00e0 con lo scopo per il quale sono stati richiesti e al fine di adattare le nostre offerte commerciali alle vostre richieste, ci\u00f2 per essere in grado di offrire un servizio pi\u00f9 personalizzato ed efficace. I campi contrassegnati con un asterisco nei moduli di registrazione da compilare sono strettamente necessari per soddisfare qualsiasi richiesta o servizio richiesto, l&#8217;inclusione dei dati nei restanti campi \u00e8 volontaria. L&#8217;utente garantisce che i dati personali forniti a PRETIUM INTERMEDIARIOS S.L. sono veritieri essi si impegnano a  comunicare eventuali cambiamenti. Il responsabile dei dati personali pu\u00f2 esercitare i diritti di accesso, rettifica, cancellazione e opposizione dei loro dati personali. Agli effetti della Politica sulla privacy il responsabile del trattamento dei dati personali \u00e8 PRETIUM INTERMEDIARIOS S.L. con sede un Valencia, Calle Almirante Cadarso, n. 14 \u2013 Porta 12.<\/p>\n<h2><strong>2. CHI \u00c8 RESPONSABILE DEL TRATTAMENTO DEI DATI?<\/strong><\/h2>\n<p>Il responsabile del trattamento \u00e8 l&#8217;ente giuridico che determina le finalit\u00e0 e le modalit\u00e0 del trattamento dei dati personali. In altre parole, il responsabile del trattamento decide come e per quali scopi vengono trattati i dati personali. Ai fini della presente Informativa sulla privacy, la persona responsabile del trattamento dei dati personali \u00e8 PRETIUM INTERMEDIARIOS, SL, con sede legale in Calle Almirante Cadarso, N\u00ba 14 &#8211; Puerta 12 (46005) &#8211; Valencia (Spagna), registrata nel Registro Mercantil de Valencia nel volume 9.498, foglio 154, foglio di registrazione n. 149462 e con NIF B-98456387.<\/p>\n<h2><strong>3. CHI E&#8217; IL TUO CONTATTO IN PRETIUM GESTI\u00d3N PER LA PROTEZIONE DEI DATI PERSONALI?<\/strong><\/h2>\n<p>Se ha domande o desidera ricevere maggiori informazioni sul trattamento o sulla protezione dei dati personali, pu\u00f2 contattarci attraverso uno dei seguenti canali: Responsabile del trattamento: PRETIUM INTERMEDIARIOS, SL, Indirizzo postale: Calle Almirante Cadarso, N\u00ba 14 &#8211; Puerta 12, 46005 Valencia Telefono: 963504708 Email: central@pretiumgestion.com Contatto DPD: central@pretiumgestion.com<br \/>\nDATI DI CONTATTO DEL DELEGATO PROTEZIONE DEI DATI<br \/>\nPer qualsiasi domanda o dubbio sulla protezione dei dati dell&#8217;utente in Pretium Gesti\u00f3n, contattare: central@pretiumgestion.com o telefonicamente al numero 963504708.<\/p>\n<h2><strong>DATOS DE CONTACTO DEL DELEGADO DE PROTECCI\u00d3N DE DATOS<\/strong><\/h2>\n<p>Para cualquier consulta o duda sobre la protecci\u00f3n de sus datos en Pretium Gesti\u00f3n, p\u00f3ngase en contacto con: central@pretiumgestion.com o a trav\u00e9s del tel\u00e9fono 963504708.<\/p>\n<h2><strong>4. CHE COSA SONO I DATI PERSONALI?<\/strong><\/h2>\n<p>I dati personali sono tutte le informazioni su una persona fisica identificata o identificabile.<\/p>\n<h2><strong>5. QUALI DATI PERSONALI SONO TRATTATI DA PRETIUM GESTI\u00d3N?<\/strong><\/h2>\n<p>Ai fini stabiliti nella presente Informativa sulla privacy, Pretium Gesti\u00f3n raccoglie ed elabora i dati personali descritti di seguito: Dati identificativi, nome, cognome, documento di identit\u00e0 (codice fiscale, numero di identificazione straniero, passaporto o permesso di soggiorno). Dati di contatto: indirizzo postale, e-mail, numero di rete fissa, numero di cellulare. Dati transazionali: informazioni su acquisti, ordini, contratti, fatturazione e incasso, metodi di pagamento, coordinate bancarie e qualsiasi dato relativo alle tue transazioni con noi. Dati elettronici: indirizzo IP, tipo e lingua del browser, dominio attraverso il quale si accede al sito Web, dati di navigazione, attivit\u00e0 sul sito Web.<\/p>\n<h2><strong>6. RACCOLTA E OTTENIMENTO DEI DATI PERSONALI.<\/strong><\/h2>\n<p>PRETIUM GESTI\u00d3N raccoglie ed elabora i dati personali che forniti volontariamente attraverso l&#8217;interazione con il nostro sito Web, in particolare: &#8211; quando si richiedono informazioni o preventivi sui nostri prodotti e servizi; &#8211; iscrivendosi alla nostra newsletter; &#8211; al momento della registrazione come utente registrato dei nostri siti Web, &#8211; al momento dell&#8217;acquisto di prodotti o servizi PRETIUM GESTI\u00d3N; Sar\u00e0 obbligato a fornire solo i dati personali necessari affinch\u00e9 PRETIUM GESTI\u00d3N possa fornire i servizi o rendere disponibili le funzionalit\u00e0 del sito Web che ha richiesto. Ad esempio, se desidera ricevere la newsletter PRETIUM GESTI\u00d3N, dovr\u00e0 fornirci la sua email. Se richiede informazioni o desidera che la contattiamo, deve fornirci le informazioni di contatto necessarie per questo scopo. Se si desidera acquistare qualsiasi prodotto o servizio che PRETIUM GESTI\u00d3N mette a disposizione sul sito Web, sar\u00e0 necessario fornirci, tra gli altri, un indirizzo fiscale per predisporre la fattura. Se non fornisce questi dati personali, sarebbe impossibile per noi fornire i nostri servizi. Nei moduli disponibili sul sito Web, i campi la cui compilazione \u00e8 obbligatoria saranno contrassegnati da un asterisco (*). Se non fornisce tutte le informazioni richieste o se riceviamo una risposta anomala o errata, non saremo in grado di rispondere alla sua richiesta o fornire il servizio o la funzionalit\u00e0 corrispondente. Lei garantisce e risponde, in ogni caso, alla veridicit\u00e0, accuratezza, validit\u00e0 e autenticit\u00e0 dei dati personali forniti e accetta di mantenerli debitamente aggiornati.<\/p>\n<p>Per navigare nel sito Web, non \u00e8 necessario fornire i dati personali. Tuttavia, quando visita il nostro sito Web, PRETIUM GESTI\u00d3N raccoglie le seguenti informazioni, automaticamente e tramite cookie e altre tecnologie di tracciamento, in base alla configurazione specifica del suo browser: indirizzo IP, tipo e identificazione del dispositivo, tipo e lingua del browser, dominio attraverso il quale si accede al sito Web, dati di navigazione, attivit\u00e0 sul sito Web. Per ulteriori informazioni, \u00e8 possibile consultare la sezione 12 della presente Informativa sulla privacy &#8220;Uso di cookie e altre tecnologie di tracciamento&#8221;. In conformit\u00e0 con le disposizioni del Regolamento europeo sulla protezione dei dati personali, 2016\/679, PRETIUM INTERMEDIARIOS, S.L. informa che ha una presenza e un collegamento sui social network: Facebook, Twitter, ecc. usati per tenere informati i propri clienti su prodotti, servizi e notizie, nonch\u00e9 su una piattaforma di iscrizione, per tutto ci\u00f2 la informiamo che: I dati raccolti attraverso questi social network sono trattati in conformit\u00e0 con i requisiti legali del Regolamento UE di protezione dei dati, se ritiene interessante essere nostro FAN \/ FOLLOWER in questo tipo di social network, sappia che seguendoci trasferisce i suoi dati su tali piattaforme e deve quindi conoscere e accettare l&#8217;uso che queste piattaforme fanno dei suoi dati. Allo stesso modo, indichiamo che PRETIUM INTERMEDIARIOS, S.L. non tratter\u00e0 i suoi dati per scopi diversi da quelli esclusivamente ed esclusivamente consentiti dall&#8217;utente e accettati, in conformit\u00e0 con il principio di qualit\u00e0 stabilito nelle normative sulla protezione dei dati.<\/p>\n<h2><strong>7. PERCHE&#8217; USIAMO I SUOI DATI PERSONALI? FINALIT\u00c0 E FONDAMENTO  GIURIDICO DEL TRATTAMENTO.<\/strong><\/h2>\n<p>In generale, i dati personali che ci fornisce vengono utilizzati per elaborare le sue richieste e transazioni, per fornire un servizio di alta qualit\u00e0 e per informarla delle opportunit\u00e0 che riteniamo possano interessarle. Gli scopi specifici per i quali trattiamo i suoi dati personali sono dettagliati di seguito: per fornire le informazioni da lei richieste, inclusi preventivi per prodotti e servizi. In questo caso, la base giuridica per il trattamento dei suoi dati \u00e8 il suo consenso. Per inviare il nostro bollettino \/ newsletter con informazioni, promozioni, campagne e notizie su prodotti e servizi PRETIUM GESTI\u00d3N e prodotti e servizi di terzi commercializzati e distribuiti da PRETIUM GESTI\u00d3N. In questo caso, la base legale per il trattamento dei suoi dati \u00e8 il suo consenso, per verificare la disponibilit\u00e0 di prodotti e servizi a domicilio o in loco. In questo caso, la base giuridica per il trattamento dei dati \u00e8 la necessit\u00e0 di applicare, su richiesta, misure precontrattuali. Per registrarsi come cliente, elaborare le sue transazioni, gestire i rapporti contrattuali con lei, darle accesso all&#8217;area privata del cliente, inviarle le informazioni pertinenti su prodotti e servizi, fatturazione, incassi e pagamenti, elaborare transazioni e metodi di pagamento e qualsiasi comunicazione di servizi o relativi al contratto e alle transazioni, amministrazione di programmi fedelt\u00e0, sconti e promozioni e conduzione di sondaggi sulla soddisfazione o relativi a prodotti e servizi commercializzati e distribuiti da PRETIUM GESTI\u00d3N. In questo caso, la base giuridica per il trattamento dei dati \u00e8, nel caso di un cliente residenziale, l&#8217;esecuzione del contratto per la vendita di prodotti o la fornitura di servizi da parte di PRETIUM GESTI\u00d3N; e, nel caso in cui il cliente \u00e8 una azienda, il nostro legittimo interesse \u00e8 fornire i nostri servizi alla societ\u00e0 o organizzazione in cui \u00e8 impiegato o fornisci servizi. Creare un account per fornire accesso all&#8217;Area privata e fornire accesso alle informazioni e ai servizi disponibili in essa: informazioni sul proprio account cliente, fatturazione e pagamenti, emissione di ordini, informazioni sui prodotti e servizi commercializzati e distribuiti da PRETIUM GESTI\u00d3N , amministrazione di programmi fedelt\u00e0, sconti e promozioni.<br \/>\nIn questo caso, la base legale per il trattamento dei suoi dati \u00e8, nel caso di un cliente residenziale, l&#8217;esecuzione del contratto per la vendita di prodotti o la fornitura di servizi con PRETIUM GESTI\u00d3N; e, nel caso in cui si tratti di una azienda, il nostro legittimo interesse a fornire i nostri servizi alla societ\u00e0 o organizzazione in cui \u00e8 impiegato o fornisce servizi. Se d\u00e0 il suo consenso, al fine di inviare comunicazioni commerciali dei nostri prodotti e servizi e dei prodotti e servizi di terzi commercializzati e distribuiti da PRETIUM GESTI\u00d3N, le inviamo le nostre pubblicazioni, sondaggi di opinione, informazioni promozionali e pubblicitarie, coupon, offerte ( incluse offerte personalizzate) e raccomandazioni di prodotti e servizi propri e di terzi commercializzati e distribuiti da PRETIUM GESTI\u00d3N, in base ai suoi interessi e sulla base di un profilo da noi preparato, per telefono, posta ordinaria, e-mail, SMS e MMS. In questo caso, la base giuridica per il trattamento dei suoi dati \u00e8 il suo consenso. Per garantire la sicurezza del nostro sito Web e delle informazioni. In questo caso, la base legale per il trattamento dei suoi dati \u00e8 il legittimo interesse a fornire un ambiente sicuro ed evitare danni ai sistemi PRETIUM GESTI\u00d3N e alle informazioni dei suoi utenti, nonch\u00e9 accesso non autorizzato e uso improprio del stessi. Per quanto riguarda le finalit\u00e0 dell&#8217;uso dei cookie, consultare la pagina &#8220;POLITICA DI UTILIZZO DEI COOKIE&#8221;. In questo caso, la base giuridica per il trattamento dei suoi dati \u00e8 il suo consenso. Quando la base del trattamento \u00e8 il consenso, puoi revocarlo in qualsiasi momento inviandoci una comunicazione a central@pretiumgestion.com con una copia del tuo ID. o documento comprovante la sua identit\u00e0, indicando il suo indirizzo a fini di comunicazione e fornendo i dettagli necessari per elaborare la sua richiesta. Pu\u00f2 sempre contattarci tramite uno qualsiasi dei canali indicati nella sezione 3 della presente Informativa sulla privacy &#8220;CHI \u00c8 IL TUO CONTATTO A GESTIONE PRETIUM PER LA PROTEZIONE DEI DATI PERSONALI?&#8221;<br \/>\nConsideri che la ricezione di informazioni commerciali non \u00e8 essenziale per mantenere il rapporto con lei. Se preferisce non ricevere comunicazioni commerciali, pu\u00f2 informarci in qualsiasi momento attraverso i canali indicati o annullare l&#8217;iscrizione al link fornito a tale scopo nelle comunicazioni commerciali via email che riceve o, se le comunicazioni vengono inviate con altri mezzi, attraverso la procedura indicata a tale scopo. In che misura il processo decisionale sar\u00e0 automatizzato? PRETIUM GESTI\u00d3N non utilizza processi decisionali completamente automatizzati per stabilire, sviluppare o interrompere un rapporto contrattuale con l&#8217;utente. Nel caso in cui utilizziamo tali processi in un caso particolare, la terremo informata e comunicheremo i suoi diritti al riguardo se richiesto dalla legge. La profilazione avr\u00e0 luogo? Per poter offrire prodotti e \/ o servizi in conformit\u00e0 con i suoi interessi e migliorare la sua esperienza di utente, potremmo preparare un &#8220;profilo commerciale&#8221; basato sulle informazioni fornite. Tuttavia, nessuna decisione automatizzata sar\u00e0 presa sulla base di quel profilo.<\/p>\n<h2><strong>8. CON CHI CONDIVIDIAMO I SUOI DATI PERSONALI?<\/strong><\/h2>\n<p>Utilizziamo, trasferiamo o condividiamo i dati personali con terzi solo nei termini descritti nella presente Informativa sulla privacy. PRETIUM GESTI\u00d3N non vende o affitta i suoi dati personali a terzi e li comunicher\u00e0 a persone o entit\u00e0 solo se otteniamo il suo consenso preventivo o in conformit\u00e0 con la legislazione applicabile quando tale consenso non \u00e8 necessario per un trasferimento specifico. Condivideremo o forniremo a terzi l&#8217;accesso ai suoi dati personali quando \u00e8 necessario per raggiungere uno degli obiettivi descritti di seguito e in conformit\u00e0 con la normativa vigente: i nostri fornitori. PRETIUM GESTI\u00d3N comunicher\u00e0 o consentir\u00e0 l&#8217;accesso ai suoi dati personali alle societ\u00e0 che ci forniscono servizi ai sensi di un contratto, quando necessario per l&#8217;adempimento degli scopi descritti nella sezione 7 della presente Informativa sulla privacy &#8220;A CHE COSA USIAMO I DATI PERSONALI? FINALIT\u00c0 E BASE GIURIDICA DEL TRATTAMENTO &#8220;. Servizi di piattaforme web, gestione ordini e trasporti, elaborazione pagamenti, distribuzione e-mail, call center, servizi di posizionamento web, marketing e organizzazione di campagne promozionali. Se uno di questi fornitori di servizi ha bisogno di accedere ai suoi dati personali, li usano solo per fornirci un servizio e in conformit\u00e0 con le nostre istruzioni. Richiediamo inoltre loro di mantenere la riservatezza e la sicurezza dei dati e di restituire o distruggere i dati quando non sono pi\u00f9 necessari. Accesso all&#8217;Area Privata. Per gestire l&#8217;accesso all&#8217;area privata del sito Web e mantenere il corretto funzionamento dei servizi offerti ai clienti, PRETIUM GESTI\u00d3N comunica al proprietario tutte le informazioni relative alle attivit\u00e0 sul conto del cliente: servizi di appalto, spese, pagamenti , spedizioni &#8230; Obblighi legali: PRETIUM GESTI\u00d3N pu\u00f2 comunicare i suoi dati personali quando il trasferimento \u00e8 autorizzato dalla legge o \u00e8 necessario per adempiere a un obbligo legale, incluso il trasferimento alle autorit\u00e0 competenti, giudici e tribunali.<\/p>\n<h2><strong>9. Quali misure applichiamo per mantenere sicuri i suoi dati personali?<\/strong><\/h2>\n<p>PRETIUM GESTI\u00d3N adotta le misure tecniche e organizzative appropriate in conformit\u00e0 con le normative vigenti per proteggere i dati personali da qualsiasi uso improprio, distruzione, perdita, modifica accidentale o illegale, divulgazione o accesso non autorizzato, compresi quelli necessari per affrontare qualsiasi sospetta violazione di dati. Il sito Web ha un sistema di autorizzazioni, utilizzando nome utente e password, attraverso il quale solo gli utenti autorizzati possono accedere all&#8217;area privata. PRETIUM GESTI\u00d3N non utilizzer\u00e0 tali informazioni in qualsiasi momento per scopi diversi dalla sua manutenzione, dalla gestione dei rapporti commerciali con l&#8217;utente e dalla fornitura dei servizi ivi disponibili. Accetti di conservare e utilizzare il nome utente con la dovuta diligenza. L&#8217;uso della password \u00e8 personale e non trasferibile e il trasferimento, anche temporaneo, a terzi non \u00e8 consentito. In questo senso, \u00e8 necessario adottare le misure necessarie per salvaguardare la password, evitando il suo utilizzo da parte di terzi. Di conseguenza, lei \u00e8 il solo responsabile dell&#8217;uso della tua password, con un risarcimento completo per PRETIUM GESTI\u00d3N. Se \u00e8 a conoscenza o sospetto dell&#8217;utilizzo della sua password da parte di terzi o che potrebbe aver luogo un uso improprio di dati personali o un accesso non autorizzato ad esso, ti preghiamo di comunicarcelo il prima possibile tramite qualsiasi dei canali indicati nella sezione 3 della presente Informativa sulla privacy &#8220;CHI \u00c8 IL SUO CONTATTO NELLA GESTIONE PRETIUM PER LA PROTEZIONE DEI DATI PERSONALI?&#8221;.<\/p>\n<h2><strong>10. PER QUANTO TEMPO CONSERVIAMO I SUOI DATI?<\/strong><\/h2>\n<p>PRETIUM GESTI\u00d3N conserver\u00e0 i suoi dati personali per il tempo necessario a soddisfare gli scopi per i quali sono stati raccolti, a condizione che lei non eserciti il diritto di eliminare o revocare il suo consenso. Saranno quindi bloccati, a meno che la legge non richieda o consenta un periodo di conservazione pi\u00f9 lungo (ad esempio, per la formulazione, l&#8217;esercizio o la difesa dei crediti), nel qual caso, saranno debitamente bloccati per il tempo necessario prima di procedere a la sua rimozione. Per determinare un periodo adeguato di conservazione dei suoi dati, applichiamo i seguenti criteri: I dati necessari per fornirti le informazioni da te richieste, comprese le stime di prodotti e servizi, saranno conservati per il tempo necessario a soddisfare ed elaborare tali richieste, in conformit\u00e0 con le disposizioni legali. applicabile e i periodi di prescrizione delle azioni previste dal regolamento. I dati necessari per inviarti la newsletter saranno elaborati fintanto che non revocher\u00e0 il suo consenso e ci informer\u00e0 del suo desiderio di non continuare a riceverli, in conformit\u00e0 con le disposizioni legali applicabili e i periodi di prescrizione delle azioni previste dal regolamento. I dati di registrazione nella nostra area privata saranno conservati per tutta la durata del contratto di servizio, a condizione che l&#8217;accesso all&#8217;area privata non venga interrotto, in conformit\u00e0 con le disposizioni legali applicabili e i periodi di prescrizione delle azioni previste dal regolamento. I dati relativi all&#8217;acquisizione di prodotti e servizi di PRETIUM GESTI\u00d3N nel quadro di un rapporto contrattuale, saranno conservati per la durata del contratto di servizio, in conformit\u00e0 con le disposizioni di legge applicabili e i periodi di prescrizione delle azioni previste dal regolamento. I dati necessari per soddisfare le vostre richieste relative ai servizi PRETIUM GESTI\u00d3N saranno conservati per il tempo necessario a soddisfare ed elaborare tali richieste, in conformit\u00e0 con le disposizioni legali applicabili e i periodi di prescrizione delle azioni previste dal regolamento. Quando ha acconsentito a ricevere comunicazioni commerciali, queste saranno conservate fintanto che non revocher\u00e0 il suo consenso e ci informer\u00e0 del suo desiderio di non continuare a riceverle, in conformit\u00e0 con le disposizioni legali applicabili e i periodi di prescrizione delle azioni previste dal regolamento. Quando i cookie sono installati sul tuo dispositivo, i dati saranno conservati in conformit\u00e0 con i requisiti legali applicabili e le raccomandazioni emesse dalle autorit\u00e0 competenti.<\/p>\n<h2><strong>11. QUALI SONO I TUOI DIRITTI SUL TRATTAMENTO DEI DATI PERSONALI?<\/strong><\/h2>\n<p>In conformit\u00e0 con le normative applicabili, ha diversi diritti in relazione alla raccolta e al trattamento dei suoi dati personali. L&#8217;esercizio di questi diritti sar\u00e0 gratuito per lei, tranne nei casi in cui vengano avanzate richieste manifestamente infondate o eccessive, in particolare per quelle ripetitive. Questi diritti sono i seguenti: Diritto all&#8217;informazione: ha il diritto di essere informato in modo conciso, trasparente, comprensibile e facilmente accessibile, con un linguaggio chiaro e semplice, sull&#8217;uso e il trattamento dei suoi dati personali. Diritto di accesso: ha il diritto di chiederci in qualsiasi momento di confermare se stiamo trattando i suoi dati personali, di fornire l&#8217;accesso a loro e le informazioni sul suo trattamento e di ottenere una copia di tali dati. La copia dei dati personali che forniamo sar\u00e0 gratuita, sebbene la richiesta di copie aggiuntive possa essere soggetta alla raccolta di un importo ragionevole basato sui costi amministrativi. Da parte nostra, potremmo chiederle di dimostrare la sua identit\u00e0 o richiedere pi\u00f9 informazioni di quelle necessarie per gestire la sua richiesta. Diritto di rettifica: ha il diritto di richiedere la rettifica di dati personali inesatti, obsoleti o incompleti che la riguardano. \u00c8 inoltre possibile richiedere il completamento di dati personali incompleti, anche mediante un&#8217;ulteriore dichiarazione.<\/p>\n<p>Diritto alla cancellazione &#8211; diritto all&#8217;oblio: hai il diritto di richiedere la cancellazione dei tuoi dati personali quando, tra le altre ragioni e fintanto che viene emesso un giudizio di proporzionalit\u00e0, i dati non sono pi\u00f9 necessari per gli scopi per i quali sono stati raccolti e non si tratta di eventi o fatti attuali e prevale il diritto all&#8217;informazione. Tuttavia, questo diritto non \u00e8 assoluto in modo che PRETIUM GESTI\u00d3N possa continuare a mantenerli debitamente bloccati nei casi previsti dalla normativa applicabile. Diritto di limitare il trattamento: ha il diritto di richiedere che limitiamo il trattamento dei suoi dati personali, il che significa che possiamo continuare a archiviarli, ma non continuare a elaborarli se viene soddisfatta una delle seguenti condizioni: che si sfida l&#8217;accuratezza dei dati, durante un periodo che consente alla persona incaricata di verificarne l&#8217;accuratezza; il trattamento \u00e8 illecito e l&#8217;utente si oppone alla cancellazione dei dati e richiede invece la limitazione del suo utilizzo; PRETIUM GESTI\u00d3N non ha pi\u00f9 bisogno dei dati ai fini del trattamento, ma \u00e8 necessario per la formulazione, l&#8217;esercizio o la difesa dei reclami; si \u00e8 opposto al trattamento, verificando se le ragioni legittime di PRETIUM GESTI\u00d3N prevalgono sulle tue.<br \/>\nDiritto alla portabilit\u00e0 dei dati: ha il diritto di trasmettere i suoi dati a un altro responsabile del trattamento in un formato strutturato, comunemente usato e leggibile da una macchina. Questo diritto si applica quando il trattamento dei dati personali si basa sul consenso o sull&#8217;esecuzione di un contratto e tale trattamento viene effettuato con mezzi automatizzati.<br \/>\nDiritto di opposizione: questo diritto consente di opporsi al trattamento dei dati personali, inclusa la creazione di profili. Non saremo in grado di occuparci dei suoi diritti solo quando elaboreremo i suoi dati nel caso in cui dimostrassimo validi motivi legittimi per il trattamento o per la formulazione, l&#8217;esercizio o la difesa dei reclami. Diritto di revoca del consenso: nei casi in cui abbiamo ottenuto il consenso per il trattamento dei dati personali dell&#8217;utente in relazione a determinate attivit\u00e0 (ad esempio, per inviare informazioni commerciali), \u00e8 possibile in qualsiasi momento la revoca. Diritto di presentare un reclamo a un&#8217;autorit\u00e0 di controllo: ha il diritto di presentare un reclamo all&#8217;Agenzia spagnola per la protezione dei dati, i cui dati sono disponibili all&#8217;indirizzo http:\/\/www.agpd.es. Puoi esercitare i suoi diritti inviandoci una comunicazione a central@pretiumgestion.com, allegando un documento comprovante la sua identit\u00e0 e fornendo i dettagli necessari per elaborare la sua richiesta.<\/p>\n<h2><strong>12. MODIFICHE<\/strong><\/h2>\n<p>PRETIUM GESTI\u00d3N pu\u00f2 modificare la politica sulla privacy per adattarla alle modifiche che possono verificarsi sul sito Web o in relazione al trattamento dei dati personali. In questo caso, PRETIUM GESTI\u00d3N la contatter\u00e0 attraverso gli abituali canali di comunicazione e con sufficiente preavviso per avvisarla delle modifiche pertinenti e le invier\u00e0 l&#8217;informativa sulla privacy aggiornata. Le versioni aggiornate e precedenti dell&#8217;Informativa sulla privacy saranno sempre disponibili sul sito Web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLITICA PER LA PROTEZIONE DEI DATI PERSONALI IN PRETIUM INTERMEDIARIOS, S.L. 1. INTRODUZIONE PRETIUM INTERMEDIARIOS S.L. informa che l&#8217;obiettivo della nostra politica sulla privacy \u00e8 proteggere al massimo livello la riservatezza dei dati personali ottenuti. PRETIUM INTERMEDIARIOS S.L. si impegna a mantenere la sicurezza dei dati forniti<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-FullWidth.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politica sulla privacy - Distacco temporaneo di lavoratori in Francia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politica sulla privacy - Distacco temporaneo di lavoratori in Francia\" \/>\n<meta property=\"og:description\" content=\"POLITICA PER LA PROTEZIONE DEI DATI PERSONALI IN PRETIUM INTERMEDIARIOS, S.L. 1. INTRODUZIONE PRETIUM INTERMEDIARIOS S.L. informa che l&#8217;obiettivo della nostra politica sulla privacy \u00e8 proteggere al massimo livello la riservatezza dei dati personali ottenuti. PRETIUM INTERMEDIARIOS S.L. si impegna a mantenere la sicurezza dei dati forniti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Distacco temporaneo di lavoratori in Francia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pretiumgestion\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-30T18:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-150px.png?fit=150%2C55&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"55\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PretiumGestion\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/\",\"name\":\"Politica sulla privacy - Distacco temporaneo di lavoratori in Francia\",\"isPartOf\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#website\"},\"datePublished\":\"2018-12-18T11:06:56+00:00\",\"dateModified\":\"2020-03-30T18:16:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/desplazamientos-francia.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politica sulla privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#website\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/\",\"name\":\"Desplazamiento temporal de trabajadores a Francia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/desplazamientos-francia.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#organization\",\"name\":\"Pretium Gesti\u00f3n\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1\",\"contentUrl\":\"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1\",\"width\":200,\"height\":73,\"caption\":\"Pretium Gesti\u00f3n\"},\"image\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pretiumgestion\",\"https:\/\/x.com\/PretiumGestion\",\"https:\/\/www.instagram.com\/pretiumgestion\/\",\"https:\/\/www.linkedin.com\/company\/pretium-gestion\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politica sulla privacy - Distacco temporaneo di lavoratori in Francia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Politica sulla privacy - Distacco temporaneo di lavoratori in Francia","og_description":"POLITICA PER LA PROTEZIONE DEI DATI PERSONALI IN PRETIUM INTERMEDIARIOS, S.L. 1. INTRODUZIONE PRETIUM INTERMEDIARIOS S.L. informa che l&#8217;obiettivo della nostra politica sulla privacy \u00e8 proteggere al massimo livello la riservatezza dei dati personali ottenuti. PRETIUM INTERMEDIARIOS S.L. si impegna a mantenere la sicurezza dei dati forniti","og_url":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/","og_site_name":"Distacco temporaneo di lavoratori in Francia","article_publisher":"https:\/\/www.facebook.com\/pretiumgestion","article_modified_time":"2020-03-30T18:16:28+00:00","og_image":[{"width":150,"height":55,"url":"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-150px.png?fit=150%2C55&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@PretiumGestion","twitter_misc":{"Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/","url":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/","name":"Politica sulla privacy - Distacco temporaneo di lavoratori in Francia","isPartOf":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#website"},"datePublished":"2018-12-18T11:06:56+00:00","dateModified":"2020-03-30T18:16:28+00:00","breadcrumb":{"@id":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desplazamientos-francia.com\/it\/politica-sulla-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desplazamientos-francia.com\/it\/"},{"@type":"ListItem","position":2,"name":"Politica sulla privacy"}]},{"@type":"WebSite","@id":"https:\/\/desplazamientos-francia.com\/it\/#website","url":"https:\/\/desplazamientos-francia.com\/it\/","name":"Desplazamiento temporal de trabajadores a Francia","description":"","publisher":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desplazamientos-francia.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/desplazamientos-francia.com\/it\/#organization","name":"Pretium Gesti\u00f3n","url":"https:\/\/desplazamientos-francia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1","contentUrl":"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1","width":200,"height":73,"caption":"Pretium Gesti\u00f3n"},"image":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pretiumgestion","https:\/\/x.com\/PretiumGestion","https:\/\/www.instagram.com\/pretiumgestion\/","https:\/\/www.linkedin.com\/company\/pretium-gestion"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PbNi1e-3","jetpack_likes_enabled":false,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/pages\/3"}],"collection":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":7,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":6405,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions\/6405"}],"wp:attachment":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}