{"id":6416,"date":"2020-04-21T13:37:41","date_gmt":"2020-04-21T11:37:41","guid":{"rendered":"https:\/\/desplazamientos-francia.com\/it\/?p=6416"},"modified":"2020-05-04T11:24:20","modified_gmt":"2020-05-04T09:24:20","slug":"coronavirus-francia-requisiti-limitazioni-distacco-lavoratori","status":"publish","type":"post","link":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/","title":{"rendered":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6417\" src=\"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?resize=600%2C337&#038;ssl=1\" alt=\"coronavirus\" width=\"600\" height=\"337\" srcset=\"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 600px) 100vw, 600px\" data-recalc-dims=\"1\" \/><\/p>\n<p>La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell&#8217;Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi. Una tale eccezionale situazione solleva dubbi,<strong> anche di carattere legale, nelle societ\u00e0 straniere all&#8217;atto del distacco dei lavoratori in Francia.<\/strong><\/p>\n<p>Il governo Macron sta <a href=\"https:\/\/pretiumgestion.com\/francia-levanta-restricciones-de-trafico-pesado-mas-tiempos-de-conduccion\/\">applicando misure dirette a frenare la pandemia<\/a> cercando un equilibrio tra la protezione della salute pubblica e il sostegno dell&#8217;attivit\u00e0 economica del Paese. In questo contesto, <strong>il distacco dei lavoratori \u00e8 autorizzato quando strettamente necessario (non essendo possibile il telelavoro).<\/strong><br \/>\n<!--more--><br \/>\nI lavoratori di societ\u00e0 straniere distaccati in Francia devono presentare un<strong> nuovo documento di distacco internazionale<\/strong> (indipendentemente dalla notifica preventiva di distacco di SIPSI). Questo documento <strong>sar\u00e0 richiesto sia alle frontiere esterne che alle frontiere interne francesi.<\/strong> Il documento prevede specificamente come uno dei requisiti essere lavoratori transfrontalieri.<\/p>\n<p>Inoltre, una volta all&#8217;interno del Paese, ogni dipendente che raggiunge il posto di lavoro deve disporre di un giustificante aziendale (Justificatif de d\u00e9placement professionnel). <strong>In caso di mancata esibizione della documentazione, le multe ammontano a \u20ac 135.<\/strong><\/p>\n<p>Una volta terminata la disposizione in Francia, le aziende devono preparare il ritorno dei lavoratori in Italia.<\/p>\n<p>In questo contesto e finch\u00e9 dura lo stato di allarme, si consentir\u00e0 l&#8217;accesso ai cittadini italiani solo via terra, e cos\u00ec ai comunitari residenti in Italia, come pure ai lavoratori transfrontalieri e a coloro che comprovino documentalmente cause di forza maggiore o situazioni di necessit\u00e0.<\/p>\n<p>Ovviamente, le misure temporanee sul coronavirus non esentano le aziende dal rispetto degli altri requisiti legali richiesti dalle normative francesi sui distacchi intracomunitari, come la nomina di un rappresentante o la notifica preventiva dei distacchi nel SIPSI.<\/p>\n<p>Se hai domande o hai bisogno di ulteriori informazioni, <strong><a href=\"https:\/\/desplazamientos-francia.com\/it\/contatto\/\">ti preghiamo di contattarci qui.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell&#8217;Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi. Una tale eccezionale situazione solleva dubbi, anche di carattere legale, nelle societ\u00e0 straniere all&#8217;atto del distacco dei lavoratori in Francia. Il<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[3],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori<\/title>\n<meta name=\"description\" content=\"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell&#039;Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori\" \/>\n<meta property=\"og:description\" content=\"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell&#039;Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\" \/>\n<meta property=\"og:site_name\" content=\"Distacco temporaneo di lavoratori in Francia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pretiumgestion\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T11:37:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-04T09:24:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg\" \/>\n<meta name=\"author\" content=\"Pretium\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PretiumGestion\" \/>\n<meta name=\"twitter:site\" content=\"@PretiumGestion\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pretium\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\"},\"author\":{\"name\":\"Pretium\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/2d00d3e1e966e7daa170426dfa7a2967\"},\"headline\":\"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori\",\"datePublished\":\"2020-04-21T11:37:41+00:00\",\"dateModified\":\"2020-05-04T09:24:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\"},\"wordCount\":302,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg\",\"articleSection\":[\"Articoli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\",\"name\":\"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori\",\"isPartOf\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg\",\"datePublished\":\"2020-04-21T11:37:41+00:00\",\"dateModified\":\"2020-05-04T09:24:20+00:00\",\"description\":\"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell'Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.\",\"breadcrumb\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/desplazamientos-francia.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#website\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/\",\"name\":\"Desplazamiento temporal de trabajadores a Francia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/desplazamientos-francia.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#organization\",\"name\":\"Pretium Gesti\u00f3n\",\"url\":\"https:\/\/desplazamientos-francia.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1\",\"contentUrl\":\"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1\",\"width\":200,\"height\":73,\"caption\":\"Pretium Gesti\u00f3n\"},\"image\":{\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pretiumgestion\",\"https:\/\/x.com\/PretiumGestion\",\"https:\/\/www.instagram.com\/pretiumgestion\/\",\"https:\/\/www.linkedin.com\/company\/pretium-gestion\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/2d00d3e1e966e7daa170426dfa7a2967\",\"name\":\"Pretium\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f29ed95c4df9e84afe22a71d2c5ce06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f29ed95c4df9e84afe22a71d2c5ce06?s=96&d=mm&r=g\",\"caption\":\"Pretium\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori","description":"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell'Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/","og_locale":"it_IT","og_type":"article","og_title":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori","og_description":"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell'Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.","og_url":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/","og_site_name":"Distacco temporaneo di lavoratori in Francia","article_publisher":"https:\/\/www.facebook.com\/pretiumgestion","article_published_time":"2020-04-21T11:37:41+00:00","article_modified_time":"2020-05-04T09:24:20+00:00","og_image":[{"url":"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg"}],"author":"Pretium","twitter_card":"summary_large_image","twitter_creator":"@PretiumGestion","twitter_site":"@PretiumGestion","twitter_misc":{"Scritto da":"Pretium","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#article","isPartOf":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/"},"author":{"name":"Pretium","@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/2d00d3e1e966e7daa170426dfa7a2967"},"headline":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori","datePublished":"2020-04-21T11:37:41+00:00","dateModified":"2020-05-04T09:24:20+00:00","mainEntityOfPage":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/"},"wordCount":302,"commentCount":0,"publisher":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#organization"},"image":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg","articleSection":["Articoli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/","url":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/","name":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori","isPartOf":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage"},"image":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg","datePublished":"2020-04-21T11:37:41+00:00","dateModified":"2020-05-04T09:24:20+00:00","description":"La grave crisi sanitaria causata dal COVID-19 ha innescato lo stato di allarme in gran parte dell'Europa, con conseguente chiusura delle frontiere e limitazione dei viaggi.","breadcrumb":{"@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#primaryimage","url":"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2020\/04\/coronavirus-francia.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/desplazamientos-francia.com\/it\/coronavirus-francia-requisiti-limitazioni-distacco-lavoratori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desplazamientos-francia.com\/it\/"},{"@type":"ListItem","position":2,"name":"CORONAVIRUS IN FRANCIA. Requisiti e limitazioni per il distacco di lavoratori"}]},{"@type":"WebSite","@id":"https:\/\/desplazamientos-francia.com\/it\/#website","url":"https:\/\/desplazamientos-francia.com\/it\/","name":"Desplazamiento temporal de trabajadores a Francia","description":"","publisher":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desplazamientos-francia.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/desplazamientos-francia.com\/it\/#organization","name":"Pretium Gesti\u00f3n","url":"https:\/\/desplazamientos-francia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1","contentUrl":"https:\/\/i1.wp.com\/desplazamientos-francia.com\/it\/wp-content\/uploads\/2019\/01\/pretium-gestion-logo-200px.png?fit=200%2C73&ssl=1","width":200,"height":73,"caption":"Pretium Gesti\u00f3n"},"image":{"@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pretiumgestion","https:\/\/x.com\/PretiumGestion","https:\/\/www.instagram.com\/pretiumgestion\/","https:\/\/www.linkedin.com\/company\/pretium-gestion"]},{"@type":"Person","@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/2d00d3e1e966e7daa170426dfa7a2967","name":"Pretium","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/desplazamientos-francia.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f29ed95c4df9e84afe22a71d2c5ce06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f29ed95c4df9e84afe22a71d2c5ce06?s=96&d=mm&r=g","caption":"Pretium"}}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbNi1e-1Fu","jetpack_likes_enabled":false,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/posts\/6416"}],"collection":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/comments?post=6416"}],"version-history":[{"count":4,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/posts\/6416\/revisions"}],"predecessor-version":[{"id":6423,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/posts\/6416\/revisions\/6423"}],"wp:attachment":[{"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/media?parent=6416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/categories?post=6416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desplazamientos-francia.com\/it\/wp-json\/wp\/v2\/tags?post=6416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}